{"id":15337,"date":"2015-03-12T08:09:57","date_gmt":"2015-03-12T08:09:57","guid":{"rendered":"http:\/\/demo.qodeinteractive.com\/bridge66\/?page_id=15337"},"modified":"2025-05-13T16:01:10","modified_gmt":"2025-05-13T14:01:10","slug":"gallery","status":"publish","type":"page","link":"https:\/\/scuolaregina.it\/index.php\/gallery\/","title":{"rendered":"Gallery"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;70&#8243; padding_bottom=&#8221;40&#8243;][vc_column][vc_separator type=&#8221;small&#8221; position=&#8221;center&#8221; up=&#8221;88&#8243; down=&#8221;0&#8243;][vc_column_text css=&#8221;.vc_custom_1745849873864{margin-top: -71px !important;}&#8221;]<\/p>\n<h3 style=\"text-align: center;\">Le nostre foto<\/h3>\n<p>[\/vc_column_text][vc_separator type=&#8221;transparent&#8221; up=&#8221;69&#8243; down=&#8221;0&#8243;]<div class=\"projects_masonry_wrapper \">\n    \n    <div class='filter_outer'>\n        <div class='filter_holder'>\n            <ul>\n                                    <li class='filter' data-filter='*'>                        <span >All<\/span>\n                    <\/li>\n                \n                                                <li class='filter' data-filter='.portfolio_category_31'>\n                                                        <span >Associazione Regina Margherita<\/span>\n                                    <\/li>\n            \n            <\/ul>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"projects_masonry_holder portfolio_main_holder gs portfolio_one_by_one\">\n        <div class=\"qode-portfolio-masonry-gallery-grid-sizer\"><\/div>\n        <div class=\"qode-portfolio-masonry-gallery-grid-gutter\"><\/div>\n\n        <article class='portfolio_masonry_item default'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/art-week-2014-malmo\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Eventi\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/art-week-2014-malmo\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/435413732_7764393723594869_5213170626566147989_n-500x500.jpg\" class=\"attachment-portfolio_masonry_regular size-portfolio_masonry_regular wp-post-image\" alt=\"\" srcset=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/435413732_7764393723594869_5213170626566147989_n-500x500.jpg 500w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/435413732_7764393723594869_5213170626566147989_n-150x150.jpg 150w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/435413732_7764393723594869_5213170626566147989_n-570x570.jpg 570w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/435413732_7764393723594869_5213170626566147989_n-1000x1000.jpg 1000w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/435413732_7764393723594869_5213170626566147989_n-650x650.jpg 650w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/435413732_7764393723594869_5213170626566147989_n-1300x1300.jpg 1300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article><article class='portfolio_masonry_item default'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/vintage-vinyl-house\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Feste\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/vintage-vinyl-house\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/479740886_9748718291829059_1623921661603400260_n-500x500.jpg\" class=\"attachment-portfolio_masonry_regular size-portfolio_masonry_regular wp-post-image\" alt=\"\" srcset=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/479740886_9748718291829059_1623921661603400260_n-500x500.jpg 500w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/479740886_9748718291829059_1623921661603400260_n-150x150.jpg 150w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/479740886_9748718291829059_1623921661603400260_n-570x570.jpg 570w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/479740886_9748718291829059_1623921661603400260_n-1000x1000.jpg 1000w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/479740886_9748718291829059_1623921661603400260_n-650x650.jpg 650w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/479740886_9748718291829059_1623921661603400260_n-1300x1300.jpg 1300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article><article class='portfolio_masonry_item large_width'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/fast-vector-mobile\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Corsi\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/fast-vector-mobile\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"500\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-1000x500.jpg\" class=\"attachment-portfolio_masonry_wide size-portfolio_masonry_wide wp-post-image\" alt=\"\" srcset=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-1000x500.jpg 1000w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-1300x650.jpg 1300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article><article class='portfolio_masonry_item large_height'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/clash-mayhem-tv\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Eventi\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/clash-mayhem-tv\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1000\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/480159407_9748718721829016_5669856324146279952_n-500x1000.jpg\" class=\"attachment-portfolio_masonry_tall size-portfolio_masonry_tall wp-post-image\" alt=\"\" srcset=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/480159407_9748718721829016_5669856324146279952_n-500x1000.jpg 500w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/480159407_9748718721829016_5669856324146279952_n-650x1300.jpg 650w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article><article class='portfolio_masonry_item portfolio_category_31 large_width'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/video-performance-festival-2014\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Festival 2014\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/video-performance-festival-2014\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"500\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/p-video-performance-festival-2014-mother-volcano-artwork-1000x500.jpg\" class=\"attachment-portfolio_masonry_wide size-portfolio_masonry_wide wp-post-image\" alt=\"qode interactive strata\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article><article class='portfolio_masonry_item portfolio_category_31 default'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/art-design-blvd\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Art &#038; Design Blvd\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/art-design-blvd\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/435087973_7763994743634767_1211758359442246408_n-500x500.jpg\" class=\"attachment-portfolio_masonry_regular size-portfolio_masonry_regular wp-post-image\" alt=\"\" srcset=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/435087973_7763994743634767_1211758359442246408_n-500x500.jpg 500w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/435087973_7763994743634767_1211758359442246408_n-150x150.jpg 150w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/435087973_7763994743634767_1211758359442246408_n-570x570.jpg 570w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/435087973_7763994743634767_1211758359442246408_n-1000x1000.jpg 1000w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/435087973_7763994743634767_1211758359442246408_n-650x650.jpg 650w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/435087973_7763994743634767_1211758359442246408_n-1300x1300.jpg 1300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article><article class='portfolio_masonry_item portfolio_category_31 default'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/der-spiegel-cover-art\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Scacchi\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/der-spiegel-cover-art\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-500x500.jpg\" class=\"attachment-portfolio_masonry_regular size-portfolio_masonry_regular wp-post-image\" alt=\"\" srcset=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-500x500.jpg 500w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-150x150.jpg 150w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-570x570.jpg 570w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-1000x1000.jpg 1000w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-650x650.jpg 650w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2025\/04\/433090957_7648809975153245_4677237201360014792_n-1300x1300.jpg 1300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article><article class='portfolio_masonry_item portfolio_category_31 large_height'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/vimeo-fx-showreel\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Musica\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/vimeo-fx-showreel\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1000\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/475763399_9719056574795231_2409541930856948319_n-500x1000.jpg\" class=\"attachment-portfolio_masonry_tall size-portfolio_masonry_tall wp-post-image\" alt=\"\" srcset=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/475763399_9719056574795231_2409541930856948319_n-500x1000.jpg 500w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/475763399_9719056574795231_2409541930856948319_n-650x1300.jpg 650w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article><article class='portfolio_masonry_item portfolio_category_31 default'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/venice-art-pavilion\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Feste\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/venice-art-pavilion\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/478518750_9699088630125359_4696678866767573406_n-500x500.jpg\" class=\"attachment-portfolio_masonry_regular size-portfolio_masonry_regular wp-post-image\" alt=\"\" srcset=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/478518750_9699088630125359_4696678866767573406_n-500x500.jpg 500w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/478518750_9699088630125359_4696678866767573406_n-150x150.jpg 150w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/478518750_9699088630125359_4696678866767573406_n-570x570.jpg 570w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/478518750_9699088630125359_4696678866767573406_n-1000x1000.jpg 1000w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/478518750_9699088630125359_4696678866767573406_n-650x650.jpg 650w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/478518750_9699088630125359_4696678866767573406_n-1300x1300.jpg 1300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article><article class='portfolio_masonry_item portfolio_category_31 default'>\n    \n    \n    \n        <div class=\"item_holder slow_zoom\">\n\n            <div class=\"text_holder\">\n    <div class=\"text_holder_outer\">\n        <div class=\"text_holder_inner\">\n            \n                \n                \n                \n            \n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"icons_holder\">\n        \n        \n                <a itemprop=\"url\" class=\"preview\" title=\"Go to Project \" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/berlin-design-week-poster\/\" data-type=\"portfolio_list\" target=\"_self\" ><\/a>\n        <\/div>\n\n                            <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Iniziative\" href=\"https:\/\/scuolaregina.it\/index.php\/portfolio_page\/berlin-design-week-poster\/\"><\/a>\n            \n            <div style=\"\" class=\"portfolio_shader\"><\/div>\n            <div class=\"image_holder\">\n                \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/WhatsApp-Image-2025-05-12-at-13.21.23-500x500.jpeg\" class=\"attachment-portfolio_masonry_regular size-portfolio_masonry_regular wp-post-image\" alt=\"\" srcset=\"https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/WhatsApp-Image-2025-05-12-at-13.21.23-500x500.jpeg 500w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/WhatsApp-Image-2025-05-12-at-13.21.23-150x150.jpeg 150w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/WhatsApp-Image-2025-05-12-at-13.21.23-570x570.jpeg 570w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/WhatsApp-Image-2025-05-12-at-13.21.23-1000x1000.jpeg 1000w, https:\/\/scuolaregina.it\/wp-content\/uploads\/2013\/10\/WhatsApp-Image-2025-05-12-at-13.21.23-650x650.jpeg 650w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span>            <\/div>\n        <\/div>\n\n    <\/article>\n    <\/div>\n<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;70&#8243; padding_bottom=&#8221;40&#8243;][vc_column][vc_separator type=&#8221;small&#8221; position=&#8221;center&#8221; up=&#8221;88&#8243; down=&#8221;0&#8243;][vc_column_text css=&#8221;.vc_custom_1745849873864{margin-top: -71px !important;}&#8221;] Le nostre foto [\/vc_column_text][vc_separator type=&#8221;transparent&#8221; up=&#8221;69&#8243; down=&#8221;0&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-15337","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/scuolaregina.it\/index.php\/wp-json\/wp\/v2\/pages\/15337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scuolaregina.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/scuolaregina.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/scuolaregina.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/scuolaregina.it\/index.php\/wp-json\/wp\/v2\/comments?post=15337"}],"version-history":[{"count":4,"href":"https:\/\/scuolaregina.it\/index.php\/wp-json\/wp\/v2\/pages\/15337\/revisions"}],"predecessor-version":[{"id":15793,"href":"https:\/\/scuolaregina.it\/index.php\/wp-json\/wp\/v2\/pages\/15337\/revisions\/15793"}],"wp:attachment":[{"href":"https:\/\/scuolaregina.it\/index.php\/wp-json\/wp\/v2\/media?parent=15337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}